{"id":655,"date":"2018-07-11T10:44:05","date_gmt":"2018-07-11T10:44:05","guid":{"rendered":"http:\/\/lexelart.com\/?p=655"},"modified":"2018-07-11T10:46:10","modified_gmt":"2018-07-11T10:46:10","slug":"produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero","status":"publish","type":"post","link":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/","title":{"rendered":"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero"},"content":{"rendered":"<h2 class=\"av-special-heading-tag \">PRODUCCIONES SOSTENIBLES<\/h2>\n<p>El grupo Lexelart, esta compuesto por dos sociedades, Lexelart S.L.U. que se dedica al control de calidad para otras empresas de la industria de la moda e International Lexelart Shoe Group, S.L. que comercializa su propia marca.<\/p>\n<p>Lexelart como fusion empresarial ha decidido renovar su plan estrategico, incorporando los valores y principios de una empresa sostenible dentro de su modelo de negocio para aportar con su actividad un valor importante a la sociedad.<\/p>\n<p>Hasta principios del a\u00f1o 2018, las actividades de ambas empresas consestian en ofrecer servicios de control, gesti\u00f3n y supervisi\u00f3n de las producciones de otras marcas en diversos paises, pudiendo llegar a fidelizar clientes tan importantes como Florsheim kids del grupo Weyco, empresa centenar de EEUU. Este logro lo habia conseguido la empresa mediante a su dedicaci\u00f3n, fiabilidad, transparencia y capacidad de gesti\u00f3n. La honestidad y seriedad de sus directivos siempre se ha ganado la confianza de sus clientes. Del mismo modo, que sus marcas propias, son populares en el mercado del calzado infantil por defender los derechos de los animales, fomentando el amor hacia la naturaleza, mediante cuentos infantiles que incorporan en sus desfiles de moda. El mundo de la inocencia de los ni\u00f1os, siempre ha sido el estandarte de la empresa, queriendo a portar lo mejor para su desarrollo.<\/p>\n<p>Impulsados siempre con una motivaci\u00f3n de ayudar y apoyar a sus clientes, el grupo Lexelart, decide hace un par de meses, en convertirse en una empresa sostenible, utilizando y recomendando materiales ecologicos y veganos a sus clientes, para preservar de este modo la vida del planeta.<\/p>\n<p>En la actualidad ya estan varios proyectos de sostenibilidad en marcha y la empresa decide invertir en esta estrategia para poder difundir el uso de materiales veganos y ecologicos y asi ofrecerle un valor a\u00f1adido a sus clientes.<\/p>\n<p>&nbsp;<\/p>\n<h2 class=\"av-special-heading-tag \">MATERIALES ECOL\u00d3GICOS<\/h2>\n<p>El grupo Lexelart, ha realizado un estudio profundo sobre los proveedores existentes que fabrican materias primas sostenibles, de los cuales, ha seleccionado a los siguientes para utilizar sus materias primas en sus producciones, este proceso va a ser gradual, donde algunos clientes ya han decidido utilizar estas materias primas de forma exclusiva y otros de forma parcial.<\/p>\n<p>El Grupo Moron, fabrica \u201cpieles\u201d veganas de microfibra, que emitan la piel animal, teniendo mayores propiedades que la piel.<\/p>\n<p>Antonio Ferre dispone de diversos tejidos totalmente ecologicos y reciclados. Boliflex, es un fabricante de suelas que solo utiliza gomas recicladas ATB, complementa la oferta de tejidos de Antonio Ferre con tejidos organicos.<\/p>\n<p><a href=\"https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/MATERIALES-ECOL\u00d3GICOS-sector-calzado.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-615 size-full\" src=\"https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/MATERIALES-ECOL\u00d3GICOS-sector-calzado.jpg\" alt=\"\" width=\"1000\" height=\"614\" srcset=\"https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/MATERIALES-ECOL\u00d3GICOS-sector-calzado.jpg 1000w, https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/MATERIALES-ECOL\u00d3GICOS-sector-calzado-300x184.jpg 300w, https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/MATERIALES-ECOL\u00d3GICOS-sector-calzado-768x472.jpg 768w, https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/MATERIALES-ECOL\u00d3GICOS-sector-calzado-705x433.jpg 705w, https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/MATERIALES-ECOL\u00d3GICOS-sector-calzado-450x276.jpg 450w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<h2 class=\"av-special-heading-tag \">MODA VEGANA<\/h2>\n<p>LEXELART, con este proyecto quiere convertirse en un referente de empresa sostenible, que recicla los residuos, colabora con su entorno social, y guia proactivamente a sus clientes a la inclusi\u00f3n de materias primas ecologicas, veganas sin origen animal y fabricadas de forma sostenible sin la emisi\u00f3n de CO2.<\/p>\n<p><strong> La moda, puede ser ecologica. Estos son algunos de los clientes de Lexelart en la actualidad:<\/strong><\/p>\n<p><a href=\"https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/clientes-moda-vegana-sector-calzado.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-614 size-full\" src=\"https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/clientes-moda-vegana-sector-calzado.jpg\" alt=\"\" width=\"1000\" height=\"466\" srcset=\"https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/clientes-moda-vegana-sector-calzado.jpg 1000w, https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/clientes-moda-vegana-sector-calzado-300x140.jpg 300w, https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/clientes-moda-vegana-sector-calzado-768x358.jpg 768w, https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/clientes-moda-vegana-sector-calzado-705x329.jpg 705w, https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/clientes-moda-vegana-sector-calzado-450x210.jpg 450w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>https:\/\/lexelart.com\/?p=655<\/p>\n","protected":false},"author":1,"featured_media":584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[8],"tags":[30,29],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"PRODUCCIONES SOSTENIBLES El grupo Lexelart, esta compuesto por dos sociedades, Lexelart S.L.U. que se dedica al control de calidad para otras empresas de la industria de la moda e International Lexelart Shoe Group, S.L. que comercializa su propia marca. Lexelart como fusion empresarial ha decidido renovar su plan estrategico, incorporando los valores y principios de\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"lexelart\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"LexelArt | Empresa Control Calidad Sector Calzado\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero | LexelArt\" \/>\n\t\t<meta property=\"og:description\" content=\"PRODUCCIONES SOSTENIBLES El grupo Lexelart, esta compuesto por dos sociedades, Lexelart S.L.U. que se dedica al control de calidad para otras empresas de la industria de la moda e International Lexelart Shoe Group, S.L. que comercializa su propia marca. Lexelart como fusion empresarial ha decidido renovar su plan estrategico, incorporando los valores y principios de\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2018-07-11T10:44:05+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-07-11T10:46:10+00:00\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/lexelart\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero | LexelArt\" \/>\n\t\t<meta name=\"twitter:description\" content=\"PRODUCCIONES SOSTENIBLES El grupo Lexelart, esta compuesto por dos sociedades, Lexelart S.L.U. que se dedica al control de calidad para otras empresas de la industria de la moda e International Lexelart Shoe Group, S.L. que comercializa su propia marca. Lexelart como fusion empresarial ha decidido renovar su plan estrategico, incorporando los valores y principios de\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#article\",\"name\":\"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero | LexelArt\",\"headline\":\"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero\",\"author\":{\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/author\\\/adminlexe\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lexelart.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/materiales-ecologicos.jpg\",\"width\":500,\"height\":333,\"caption\":\"https:\\\/\\\/lexelart.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/materiales-ecologicos.jpg\"},\"datePublished\":\"2018-07-11T10:44:05+00:00\",\"dateModified\":\"2018-07-11T10:46:10+00:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#webpage\"},\"articleSection\":\"controllo qualit\\u00e0 industria calzaturiera @it, materiali ecologici e moda vegana nel settore calzaturiero, Produzioni sostenibili settore calzaturiero, Galleria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lexelart.com\\\/it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/category\\\/controllo-qualita-industria-calzaturiera-it\\\/#listItem\",\"name\":\"controllo qualit\\u00e0 industria calzaturiera @it\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/category\\\/controllo-qualita-industria-calzaturiera-it\\\/#listItem\",\"position\":2,\"name\":\"controllo qualit\\u00e0 industria calzaturiera @it\",\"item\":\"https:\\\/\\\/lexelart.com\\\/it\\\/category\\\/controllo-qualita-industria-calzaturiera-it\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#listItem\",\"name\":\"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#listItem\",\"position\":3,\"name\":\"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/category\\\/controllo-qualita-industria-calzaturiera-it\\\/#listItem\",\"name\":\"controllo qualit\\u00e0 industria calzaturiera @it\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/#organization\",\"name\":\"LexelArt\",\"description\":\"Empresa Control Calidad Sector Calzado\",\"url\":\"https:\\\/\\\/lexelart.com\\\/it\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/author\\\/adminlexe\\\/#author\",\"url\":\"https:\\\/\\\/lexelart.com\\\/it\\\/author\\\/adminlexe\\\/\",\"name\":\"lexelart\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a0e05600b39fdae98f71d18496acd7e1?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"lexelart\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/lexelart\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lexelart\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@Lealeloshoes\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/susana-mazzarino-jimenez-2b687413\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#webpage\",\"url\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/\",\"name\":\"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero | LexelArt\",\"description\":\"PRODUCCIONES SOSTENIBLES El grupo Lexelart, esta compuesto por dos sociedades, Lexelart S.L.U. que se dedica al control de calidad para otras empresas de la industria de la moda e International Lexelart Shoe Group, S.L. que comercializa su propia marca. Lexelart como fusion empresarial ha decidido renovar su plan estrategico, incorporando los valores y principios de\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/author\\\/adminlexe\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/author\\\/adminlexe\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/lexelart.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/materiales-ecologicos.jpg\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#mainImage\",\"width\":500,\"height\":333,\"caption\":\"https:\\\/\\\/lexelart.com\\\/wp-content\\\/uploads\\\/2018\\\/07\\\/materiales-ecologicos.jpg\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\\\/#mainImage\"},\"datePublished\":\"2018-07-11T10:44:05+00:00\",\"dateModified\":\"2018-07-11T10:46:10+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/lexelart.com\\\/it\\\/\",\"name\":\"LexelArt\",\"description\":\"Empresa Control Calidad Sector Calzado\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/lexelart.com\\\/it\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero | LexelArt","description":"PRODUCCIONES SOSTENIBLES El grupo Lexelart, esta compuesto por dos sociedades, Lexelart S.L.U. que se dedica al control de calidad para otras empresas de la industria de la moda e International Lexelart Shoe Group, S.L. que comercializa su propia marca. Lexelart como fusion empresarial ha decidido renovar su plan estrategico, incorporando los valores y principios de","canonical_url":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#article","name":"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero | LexelArt","headline":"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero","author":{"@id":"https:\/\/lexelart.com\/it\/author\/adminlexe\/#author"},"publisher":{"@id":"https:\/\/lexelart.com\/it\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/materiales-ecologicos.jpg","width":500,"height":333,"caption":"https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/materiales-ecologicos.jpg"},"datePublished":"2018-07-11T10:44:05+00:00","dateModified":"2018-07-11T10:46:10+00:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#webpage"},"isPartOf":{"@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#webpage"},"articleSection":"controllo qualit\u00e0 industria calzaturiera @it, materiali ecologici e moda vegana nel settore calzaturiero, Produzioni sostenibili settore calzaturiero, Galleria"},{"@type":"BreadcrumbList","@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/lexelart.com\/it\/#listItem","position":1,"name":"Home","item":"https:\/\/lexelart.com\/it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lexelart.com\/it\/category\/controllo-qualita-industria-calzaturiera-it\/#listItem","name":"controllo qualit\u00e0 industria calzaturiera @it"}},{"@type":"ListItem","@id":"https:\/\/lexelart.com\/it\/category\/controllo-qualita-industria-calzaturiera-it\/#listItem","position":2,"name":"controllo qualit\u00e0 industria calzaturiera @it","item":"https:\/\/lexelart.com\/it\/category\/controllo-qualita-industria-calzaturiera-it\/","nextItem":{"@type":"ListItem","@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#listItem","name":"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero"},"previousItem":{"@type":"ListItem","@id":"https:\/\/lexelart.com\/it\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#listItem","position":3,"name":"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero","previousItem":{"@type":"ListItem","@id":"https:\/\/lexelart.com\/it\/category\/controllo-qualita-industria-calzaturiera-it\/#listItem","name":"controllo qualit\u00e0 industria calzaturiera @it"}}]},{"@type":"Organization","@id":"https:\/\/lexelart.com\/it\/#organization","name":"LexelArt","description":"Empresa Control Calidad Sector Calzado","url":"https:\/\/lexelart.com\/it\/"},{"@type":"Person","@id":"https:\/\/lexelart.com\/it\/author\/adminlexe\/#author","url":"https:\/\/lexelart.com\/it\/author\/adminlexe\/","name":"lexelart","image":{"@type":"ImageObject","@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a0e05600b39fdae98f71d18496acd7e1?s=96&d=mm&r=g","width":96,"height":96,"caption":"lexelart"},"sameAs":["https:\/\/www.facebook.com\/lexelart\/","https:\/\/www.instagram.com\/lexelart\/","https:\/\/www.youtube.com\/@Lealeloshoes","https:\/\/www.linkedin.com\/in\/susana-mazzarino-jimenez-2b687413\/"]},{"@type":"WebPage","@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#webpage","url":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/","name":"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero | LexelArt","description":"PRODUCCIONES SOSTENIBLES El grupo Lexelart, esta compuesto por dos sociedades, Lexelart S.L.U. que se dedica al control de calidad para otras empresas de la industria de la moda e International Lexelart Shoe Group, S.L. que comercializa su propia marca. Lexelart como fusion empresarial ha decidido renovar su plan estrategico, incorporando los valores y principios de","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/lexelart.com\/it\/#website"},"breadcrumb":{"@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#breadcrumblist"},"author":{"@id":"https:\/\/lexelart.com\/it\/author\/adminlexe\/#author"},"creator":{"@id":"https:\/\/lexelart.com\/it\/author\/adminlexe\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/materiales-ecologicos.jpg","@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#mainImage","width":500,"height":333,"caption":"https:\/\/lexelart.com\/wp-content\/uploads\/2018\/07\/materiales-ecologicos.jpg"},"primaryImageOfPage":{"@id":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/#mainImage"},"datePublished":"2018-07-11T10:44:05+00:00","dateModified":"2018-07-11T10:46:10+00:00"},{"@type":"WebSite","@id":"https:\/\/lexelart.com\/it\/#website","url":"https:\/\/lexelart.com\/it\/","name":"LexelArt","description":"Empresa Control Calidad Sector Calzado","inLanguage":"it-IT","publisher":{"@id":"https:\/\/lexelart.com\/it\/#organization"}}]},"og:locale":"it_IT","og:site_name":"LexelArt | Empresa Control Calidad Sector Calzado","og:type":"article","og:title":"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero | LexelArt","og:description":"PRODUCCIONES SOSTENIBLES El grupo Lexelart, esta compuesto por dos sociedades, Lexelart S.L.U. que se dedica al control de calidad para otras empresas de la industria de la moda e International Lexelart Shoe Group, S.L. que comercializa su propia marca. Lexelart como fusion empresarial ha decidido renovar su plan estrategico, incorporando los valores y principios de","og:url":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/","article:published_time":"2018-07-11T10:44:05+00:00","article:modified_time":"2018-07-11T10:46:10+00:00","article:author":"https:\/\/www.facebook.com\/lexelart\/","twitter:card":"summary","twitter:title":"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero | LexelArt","twitter:description":"PRODUCCIONES SOSTENIBLES El grupo Lexelart, esta compuesto por dos sociedades, Lexelart S.L.U. que se dedica al control de calidad para otras empresas de la industria de la moda e International Lexelart Shoe Group, S.L. que comercializa su propia marca. Lexelart como fusion empresarial ha decidido renovar su plan estrategico, incorporando los valores y principios de"},"aioseo_meta_data":{"post_id":"655","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2020-12-21 12:30:56","updated":"2025-06-04 09:29:41"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lexelart.com\/it\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/lexelart.com\/it\/category\/controllo-qualita-industria-calzaturiera-it\/\" title=\"controllo qualit\u00e0 industria calzaturiera @it\">controllo qualit\u00e0 industria calzaturiera @it<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tProduzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/lexelart.com\/it\/"},{"label":"controllo qualit\u00e0 industria calzaturiera @it","link":"https:\/\/lexelart.com\/it\/category\/controllo-qualita-industria-calzaturiera-it\/"},{"label":"Produzioni sostenibili, materiali ecologici e moda vegana nel settore calzaturiero","link":"https:\/\/lexelart.com\/it\/produzioni-sostenibili-materiali-ecologici-e-moda-vegana-nel-settore-calzaturiero\/"}],"_links":{"self":[{"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/posts\/655"}],"collection":[{"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/comments?post=655"}],"version-history":[{"count":1,"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/posts\/655\/revisions"}],"predecessor-version":[{"id":657,"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/posts\/655\/revisions\/657"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/media\/584"}],"wp:attachment":[{"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/media?parent=655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/categories?post=655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lexelart.com\/it\/wp-json\/wp\/v2\/tags?post=655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}